{"id":10278,"date":"2026-08-30T18:35:49","date_gmt":"2026-08-30T16:35:49","guid":{"rendered":"https:\/\/leibniz-gymnasium.de\/?post_type=tribe_events&#038;p=10278"},"modified":"2026-08-30T18:35:49","modified_gmt":"2026-08-30T16:35:49","slug":"1-konferenz-der-lehrkraefte-3","status":"publish","type":"tribe_events","link":"https:\/\/leibniz-gymnasium.de\/index.php\/event\/1-konferenz-der-lehrkraefte-3\/","title":{"rendered":"1. Konferenz der Lehrkr\u00e4fte"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-10278","tribe_events","type-tribe_events","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"MartinaJank\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/leibniz-gymnasium.de\/index.php\/event\/1-konferenz-der-lehrkraefte-3\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Wir schaffen Zukunft - Just another WordPress site\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"1. Konferenz der Lehrkr\u00e4fte - Wir schaffen Zukunft\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/leibniz-gymnasium.de\/index.php\/event\/1-konferenz-der-lehrkraefte-3\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-08-30T16:35:49+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-08-30T16:35:49+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"1. Konferenz der Lehrkr\u00e4fte - Wir schaffen Zukunft\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/leibniz-gymnasium.de\\\/index.php\\\/event\\\/1-konferenz-der-lehrkraefte-3\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/leibniz-gymnasium.de#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/leibniz-gymnasium.de\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/leibniz-gymnasium.de\\\/index.php\\\/events\\\/#listItem\",\"name\":\"Veranstaltungen\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/leibniz-gymnasium.de\\\/index.php\\\/events\\\/#listItem\",\"position\":2,\"name\":\"Veranstaltungen\",\"item\":\"https:\\\/\\\/leibniz-gymnasium.de\\\/index.php\\\/events\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/leibniz-gymnasium.de\\\/index.php\\\/event\\\/1-konferenz-der-lehrkraefte-3\\\/#listItem\",\"name\":\"1. Konferenz der Lehrkr\\u00e4fte\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/leibniz-gymnasium.de#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/leibniz-gymnasium.de\\\/index.php\\\/event\\\/1-konferenz-der-lehrkraefte-3\\\/#listItem\",\"position\":3,\"name\":\"1. Konferenz der Lehrkr\\u00e4fte\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/leibniz-gymnasium.de\\\/index.php\\\/events\\\/#listItem\",\"name\":\"Veranstaltungen\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/leibniz-gymnasium.de\\\/#organization\",\"name\":\"arvidstrasser.com\",\"description\":\"Just another WordPress site\",\"url\":\"https:\\\/\\\/leibniz-gymnasium.de\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/leibniz-gymnasium.de\\\/index.php\\\/author\\\/martinajank\\\/#author\",\"url\":\"https:\\\/\\\/leibniz-gymnasium.de\\\/index.php\\\/author\\\/martinajank\\\/\",\"name\":\"MartinaJank\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/leibniz-gymnasium.de\\\/index.php\\\/event\\\/1-konferenz-der-lehrkraefte-3\\\/#webpage\",\"url\":\"https:\\\/\\\/leibniz-gymnasium.de\\\/index.php\\\/event\\\/1-konferenz-der-lehrkraefte-3\\\/\",\"name\":\"1. Konferenz der Lehrkr\\u00e4fte - Wir schaffen Zukunft\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leibniz-gymnasium.de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/leibniz-gymnasium.de\\\/index.php\\\/event\\\/1-konferenz-der-lehrkraefte-3\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/leibniz-gymnasium.de\\\/index.php\\\/author\\\/martinajank\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/leibniz-gymnasium.de\\\/index.php\\\/author\\\/martinajank\\\/#author\"},\"datePublished\":\"2026-08-30T18:35:49+02:00\",\"dateModified\":\"2026-08-30T18:35:49+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/leibniz-gymnasium.de\\\/#website\",\"url\":\"https:\\\/\\\/leibniz-gymnasium.de\\\/\",\"name\":\"Wir schaffen Zukunft\",\"description\":\"Just another WordPress site\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/leibniz-gymnasium.de\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"1. Konferenz der Lehrkr\u00e4fte - Wir schaffen Zukunft","description":"","canonical_url":"https:\/\/leibniz-gymnasium.de\/index.php\/event\/1-konferenz-der-lehrkraefte-3\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/leibniz-gymnasium.de\/index.php\/event\/1-konferenz-der-lehrkraefte-3\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/leibniz-gymnasium.de#listItem","position":1,"name":"Home","item":"https:\/\/leibniz-gymnasium.de","nextItem":{"@type":"ListItem","@id":"https:\/\/leibniz-gymnasium.de\/index.php\/events\/#listItem","name":"Veranstaltungen"}},{"@type":"ListItem","@id":"https:\/\/leibniz-gymnasium.de\/index.php\/events\/#listItem","position":2,"name":"Veranstaltungen","item":"https:\/\/leibniz-gymnasium.de\/index.php\/events\/","nextItem":{"@type":"ListItem","@id":"https:\/\/leibniz-gymnasium.de\/index.php\/event\/1-konferenz-der-lehrkraefte-3\/#listItem","name":"1. Konferenz der Lehrkr\u00e4fte"},"previousItem":{"@type":"ListItem","@id":"https:\/\/leibniz-gymnasium.de#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/leibniz-gymnasium.de\/index.php\/event\/1-konferenz-der-lehrkraefte-3\/#listItem","position":3,"name":"1. Konferenz der Lehrkr\u00e4fte","previousItem":{"@type":"ListItem","@id":"https:\/\/leibniz-gymnasium.de\/index.php\/events\/#listItem","name":"Veranstaltungen"}}]},{"@type":"Organization","@id":"https:\/\/leibniz-gymnasium.de\/#organization","name":"arvidstrasser.com","description":"Just another WordPress site","url":"https:\/\/leibniz-gymnasium.de\/"},{"@type":"Person","@id":"https:\/\/leibniz-gymnasium.de\/index.php\/author\/martinajank\/#author","url":"https:\/\/leibniz-gymnasium.de\/index.php\/author\/martinajank\/","name":"MartinaJank"},{"@type":"WebPage","@id":"https:\/\/leibniz-gymnasium.de\/index.php\/event\/1-konferenz-der-lehrkraefte-3\/#webpage","url":"https:\/\/leibniz-gymnasium.de\/index.php\/event\/1-konferenz-der-lehrkraefte-3\/","name":"1. Konferenz der Lehrkr\u00e4fte - Wir schaffen Zukunft","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/leibniz-gymnasium.de\/#website"},"breadcrumb":{"@id":"https:\/\/leibniz-gymnasium.de\/index.php\/event\/1-konferenz-der-lehrkraefte-3\/#breadcrumblist"},"author":{"@id":"https:\/\/leibniz-gymnasium.de\/index.php\/author\/martinajank\/#author"},"creator":{"@id":"https:\/\/leibniz-gymnasium.de\/index.php\/author\/martinajank\/#author"},"datePublished":"2026-08-30T18:35:49+02:00","dateModified":"2026-08-30T18:35:49+02:00"},{"@type":"WebSite","@id":"https:\/\/leibniz-gymnasium.de\/#website","url":"https:\/\/leibniz-gymnasium.de\/","name":"Wir schaffen Zukunft","description":"Just another WordPress site","inLanguage":"de-DE","publisher":{"@id":"https:\/\/leibniz-gymnasium.de\/#organization"}}]},"og:locale":"de_DE","og:site_name":"Wir schaffen Zukunft - Just another WordPress site","og:type":"article","og:title":"1. Konferenz der Lehrkr\u00e4fte - Wir schaffen Zukunft","og:url":"https:\/\/leibniz-gymnasium.de\/index.php\/event\/1-konferenz-der-lehrkraefte-3\/","article:published_time":"2026-08-30T16:35:49+00:00","article:modified_time":"2026-08-30T16:35:49+00:00","twitter:card":"summary","twitter:title":"1. Konferenz der Lehrkr\u00e4fte - Wir schaffen Zukunft"},"aioseo_meta_data":{"post_id":"10278","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":{"subject":"","preview":"","content":""},"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-08-30 16:35:49","updated":"2026-08-30 16:36:49","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/leibniz-gymnasium.de\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/leibniz-gymnasium.de\/index.php\/events\/\" title=\"Veranstaltungen\">Veranstaltungen<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t1. Konferenz der Lehrkr\u00e4fte\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/leibniz-gymnasium.de"},{"label":"Veranstaltungen","link":"https:\/\/leibniz-gymnasium.de\/index.php\/events\/"},{"label":"1. Konferenz der Lehrkr\u00e4fte","link":"https:\/\/leibniz-gymnasium.de\/index.php\/event\/1-konferenz-der-lehrkraefte-3\/"}],"_links":{"self":[{"href":"https:\/\/leibniz-gymnasium.de\/index.php\/wp-json\/wp\/v2\/tribe_events\/10278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leibniz-gymnasium.de\/index.php\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/leibniz-gymnasium.de\/index.php\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/leibniz-gymnasium.de\/index.php\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":1,"href":"https:\/\/leibniz-gymnasium.de\/index.php\/wp-json\/wp\/v2\/tribe_events\/10278\/revisions"}],"predecessor-version":[{"id":10279,"href":"https:\/\/leibniz-gymnasium.de\/index.php\/wp-json\/wp\/v2\/tribe_events\/10278\/revisions\/10279"}],"wp:attachment":[{"href":"https:\/\/leibniz-gymnasium.de\/index.php\/wp-json\/wp\/v2\/media?parent=10278"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/leibniz-gymnasium.de\/index.php\/wp-json\/wp\/v2\/tags?post=10278"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/leibniz-gymnasium.de\/index.php\/wp-json\/wp\/v2\/tribe_events_cat?post=10278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}